{"id":223,"count":0,"description":"<strong>Clique no Link<\/strong> para <em>acessar<\/em> a <strong>loja<\/strong> de<strong> <em>Produtos f\u00edsicos:<\/em><\/strong>\r\n<h1><strong><a href=\"http:\/\/promo.familyhastools.com\/\" target=\"_blank\" rel=\"noopener\">Loja<\/a><\/strong><\/h1>\r\nTemos camisetas masculinas, femininas, infantis e para beb\u00eas, canecas, bon\u00e9s, sacolas, entre outros.\r\n\r\n<strong>Expresse seus valores<\/strong> com <em>criatividade e beleza<\/em> usando os<em><strong> <a href=\"https:\/\/montink.com\/family-has-tools-\/\" target=\"_blank\" rel=\"noopener\">designs autorais<\/a><\/strong><\/em> da minha nova loja de produtos f\u00edsicos.\r\n\r\n<a href=\"https:\/\/montink.com\/family-has-tools-\/\" target=\"_blank\" rel=\"noopener\"><img class=\"aligncenter size-full wp-image-8962\" src=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2023\/05\/16.png\" alt=\"\" width=\"1215\" height=\"1215\" \/><\/a>","link":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/","name":"Produtos f\u00edsicos","slug":"produtos-fisicos","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":14,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Produtos f\u00edsicos - Family Has Tools<\/title>\n<meta name=\"description\" content=\"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Produtos f\u00edsicos - Family Has Tools\" \/>\n<meta property=\"og:description\" content=\"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Family Has Tools\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2023\/05\/16.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/product-category\\\/produtos-fisicos\\\/\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/product-category\\\/produtos-fisicos\\\/\",\"name\":\"Arquivos Produtos f\u00edsicos - Family Has Tools\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#website\"},\"description\":\"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/product-category\\\/produtos-fisicos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/product-category\\\/produtos-fisicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.familyhastools.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos f\u00edsicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#website\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/\",\"name\":\"Family Has Tools\",\"description\":\"A jornada de nossa familia homeschooler\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familyhastools.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#organization\",\"name\":\"Family Has Tools\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-com-Arthur-_grande.png\",\"contentUrl\":\"https:\\\/\\\/www.familyhastools.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-com-Arthur-_grande.png\",\"width\":2350,\"height\":1000,\"caption\":\"Family Has Tools\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Produtos f\u00edsicos - Family Has Tools","description":"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Produtos f\u00edsicos - Family Has Tools","og_description":"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.","og_url":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/","og_site_name":"Family Has Tools","og_image":[{"url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2023\/05\/16.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/","url":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/","name":"Arquivos Produtos f\u00edsicos - Family Has Tools","isPartOf":{"@id":"https:\/\/www.familyhastools.com\/#website"},"description":"Expresse seu valores com criatividade e beleza usando designs autorais da minha nova loja de produtos f\u00edsicos pensado para fam\u00edlias.","breadcrumb":{"@id":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.familyhastools.com\/index.php\/product-category\/produtos-fisicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.familyhastools.com\/"},{"@type":"ListItem","position":2,"name":"Produtos f\u00edsicos"}]},{"@type":"WebSite","@id":"https:\/\/www.familyhastools.com\/#website","url":"https:\/\/www.familyhastools.com\/","name":"Family Has Tools","description":"A jornada de nossa familia homeschooler","publisher":{"@id":"https:\/\/www.familyhastools.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familyhastools.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.familyhastools.com\/#organization","name":"Family Has Tools","url":"https:\/\/www.familyhastools.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","contentUrl":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","width":2350,"height":1000,"caption":"Family Has Tools"},"image":{"@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product_cat\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}