{"id":3337,"date":"2020-10-10T00:43:07","date_gmt":"2020-10-10T00:43:07","guid":{"rendered":"https:\/\/www.familyhastools.com\/?post_type=product&#038;p=3337"},"modified":"2023-09-27T20:38:43","modified_gmt":"2023-09-27T20:38:43","slug":"3337","status":"publish","type":"product","link":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/","title":{"rendered":"Aprecia\u00e7\u00e3o de Arte : Edgar Degas"},"content":{"rendered":"<p>Arquivo Digital : PDF<\/p>\n<p>Esse material \u00e9 algo \u00fanico e exclusivo,\u00a0 fruto da parceria entre FamilyHasTools e Mosaika Escola de Arte.<\/p>\n<p>Eu e a Carol, resolvemos juntar a nossa experi\u00eancia da aprecia\u00e7\u00e3o art\u00edstica em nossas casas com o conhecimento t\u00e9cnico e pr\u00e1tico da arte educadora C\u00e1tia Usevicius Maia da <em>Mosaika Escola de Arte<\/em> para trazer especialmente esse material para voc\u00eas.<\/p>\n<p><strong>O material visa auxiliar os pais a ensinarem uma aprecia\u00e7\u00e3o dirigida de obras de arte e a fazerem atividades pr\u00e1ticas que fixem o per\u00edodo hist\u00f3rico da arte \u00e0 que pertence o artista.<\/strong><\/p>\n<p>Al\u00e9m de dar ferramentas para que os pais compreendam as caracter\u00edsticas das obras do artista e o per\u00edodo em que ele est\u00e1 inserido, o material contem <strong>v\u00eddeos pr\u00e1ticos<\/strong>\u00a0 de atividades para fazer com seus filhos.<\/p>\n<p><strong>Um material completo para quem quer apreciar de forma pr\u00e1tica as obras deste grande artista e estudar o per\u00edodo da arte \u00e0 que ele pertence .<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Veja alguns detalhes:<\/p>\n<p>Aqui<\/p>\n<p>https:\/\/www.instagram.com\/p\/CGS7J8rp1t5\/?utm_source=ig_web_copy_link<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Inclui:<\/strong><\/p>\n<table width=\"500\">\n<tbody>\n<tr>\n<td width=\"500\">Orienta\u00e7\u00f5es gerais para o uso do material<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Sugest\u00f5es para observa\u00e7\u00e3o dirigida das obras<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">&#8211; Obra: A Estrela<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">&#8211; Obra: Os Bastidores da Dan\u00e7a<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Orienta\u00e7\u00f5es para os pais<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Sugest\u00f5es de Atividades Extras:<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">-Atividade 1<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">-Atividade 2<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">-Atividade 3 e links para os v\u00eddeos 1 e 2<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Um pouco sobre Hilaire German Edgar Degas<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Obras para aprecia\u00e7\u00e3o<\/td>\n<\/tr>\n<tr>\n<td width=\"500\">Obras em formato cart\u00e3o<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Venha enriquecer o aprendizado de seus filhos com esse material \u00fanico e exclusivo que ir\u00e1 proporcionar um olhar diferenciado \u00e0 experi\u00eancia de arte da sua fam\u00edlia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arquivo Digital : PDF Esse material \u00e9 algo \u00fanico e exclusivo,\u00a0 fruto da parceria entre FamilyHasTools e Mosaika Escola de Arte. Eu e a Carol, resolvemos juntar a nossa experi\u00eancia da aprecia\u00e7\u00e3o art\u00edstica em nossas casas com o conhecimento t\u00e9cnico e pr\u00e1tico da arte educadora C\u00e1tia Usevicius Maia da Mosaika Escola de Arte para trazer [&hellip;]<\/p>\n","protected":false},"featured_media":3340,"template":"","meta":[],"product_brand":[],"product_cat":[410,412,407,409,283],"product_tag":[292,284,285,290,289,291,241,286,118,119,120,177,287,288,130,171,121,127],"class_list":{"0":"post-3337","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-5-8-anos","7":"product_cat-9-14-anos","8":"product_cat-para-familia-toda","9":"product_cat-adultos","10":"product_cat-arte","11":"product_tag-apostila-de-arte","12":"product_tag-apreciacao-de-arte","13":"product_tag-arte","14":"product_tag-arte-para-criancas","15":"product_tag-artistas-impressionistas","16":"product_tag-atividas-edgar-degas","17":"product_tag-charlotte-mason","18":"product_tag-edgar-degar","19":"product_tag-educacao-domiciliar","20":"product_tag-ensino-domiciliar","21":"product_tag-family-has-tools","22":"product_tag-familyhastools","23":"product_tag-impressionismo","24":"product_tag-impressionista","25":"product_tag-material-de-apoio","26":"product_tag-material-didatico","27":"product_tag-rachel-haswell","28":"product_tag-unidade-de-estudo","30":"first","31":"instock","32":"downloadable","33":"virtual","34":"purchasable","35":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools<\/title>\n<meta name=\"description\" content=\"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools\" \/>\n<meta property=\"og:description\" content=\"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/\" \/>\n<meta property=\"og:site_name\" content=\"Family Has Tools\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T20:38:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/\",\"url\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/\",\"name\":\"Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools\",\"isPartOf\":{\"@id\":\"https:\/\/www.familyhastools.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png\",\"datePublished\":\"2020-10-10T00:43:07+00:00\",\"dateModified\":\"2023-09-27T20:38:43+00:00\",\"description\":\"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence\",\"breadcrumb\":{\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage\",\"url\":\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png\",\"contentUrl\":\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.familyhastools.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/www.familyhastools.com\/index.php\/loja-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aprecia\u00e7\u00e3o de Arte : Edgar Degas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.familyhastools.com\/#website\",\"url\":\"https:\/\/www.familyhastools.com\/\",\"name\":\"Family Has Tools\",\"description\":\"A jornada de nossa familia homeschooler\",\"publisher\":{\"@id\":\"https:\/\/www.familyhastools.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.familyhastools.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.familyhastools.com\/#organization\",\"name\":\"Family Has Tools\",\"url\":\"https:\/\/www.familyhastools.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png\",\"contentUrl\":\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png\",\"width\":2350,\"height\":1000,\"caption\":\"Family Has Tools\"},\"image\":{\"@id\":\"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools","description":"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools","og_description":"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence","og_url":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/","og_site_name":"Family Has Tools","article_modified_time":"2023-09-27T20:38:43+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/","url":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/","name":"Aprecia\u00e7\u00e3o de Arte : Edgar Degas - Family Has Tools","isPartOf":{"@id":"https:\/\/www.familyhastools.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage"},"image":{"@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage"},"thumbnailUrl":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png","datePublished":"2020-10-10T00:43:07+00:00","dateModified":"2023-09-27T20:38:43+00:00","description":"Um material completo para quem quer apreciar de forma pr\u00e1tica mais as obras deste grande artista, Edgar Degas e estudar o per\u00edodo da arte \u00e0 que ele pertence","breadcrumb":{"@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familyhastools.com\/index.php\/product\/3337\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#primaryimage","url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png","contentUrl":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/10\/Aprecia\u00e7\u00e3o-de-Arte-Degas.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.familyhastools.com\/index.php\/product\/3337\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.familyhastools.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/www.familyhastools.com\/index.php\/loja-2\/"},{"@type":"ListItem","position":3,"name":"Aprecia\u00e7\u00e3o de Arte : Edgar Degas"}]},{"@type":"WebSite","@id":"https:\/\/www.familyhastools.com\/#website","url":"https:\/\/www.familyhastools.com\/","name":"Family Has Tools","description":"A jornada de nossa familia homeschooler","publisher":{"@id":"https:\/\/www.familyhastools.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familyhastools.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.familyhastools.com\/#organization","name":"Family Has Tools","url":"https:\/\/www.familyhastools.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","contentUrl":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","width":2350,"height":1000,"caption":"Family Has Tools"},"image":{"@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product\/3337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/media\/3340"}],"wp:attachment":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/media?parent=3337"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=3337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=3337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=3337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}