{"id":1132,"date":"2018-08-03T16:47:28","date_gmt":"2018-08-03T16:47:28","guid":{"rendered":"http:\/\/familyhastools.com\/?p=1132"},"modified":"2018-08-03T17:43:27","modified_gmt":"2018-08-03T17:43:27","slug":"1132","status":"publish","type":"post","link":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/","title":{"rendered":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica"},"content":{"rendered":"<p>Esse produto foi desenvolvido especialmente para auxilar nas li\u00e7\u00f5es de matem\u00e1tica e facilitar o aprendizado.<\/p>\n<p><a href=\"https:\/\/pay.hotmart.com\/M8444470N\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1059\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-300x63.png\" alt=\"\" width=\"300\" height=\"63\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-300x63.png 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-416x88.png 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui.png 487w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Nele est\u00e3o inclusos:<\/p>\n<ul>\n<li>Flash cards: n\u00fameros 0 a 30.<\/li>\n<li>Livros dos n\u00fameros: 0 a 30 (onde a crian\u00e7a pode usar a criatividade para preencher o livro e fixar o conceito numeral).<\/li>\n<li>Flash cards Jumbo: n\u00fameros 0 a 30. (possui adicional com n\u00fameros com setas)<\/li>\n<li>Folha de estudo num\u00e9rico.<\/li>\n<\/ul>\n<p>Arquivo em PDF<\/p>\n<p>Download imediato ap\u00f3s confirma\u00e7\u00e3o de pagamento.<\/p>\n<p>veja os detalhes nas imagens :<\/p>\n<p><a href=\"https:\/\/pay.hotmart.com\/M8444470N\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1059\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-300x63.png\" alt=\"\" width=\"300\" height=\"63\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-300x63.png 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui-416x88.png 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/01\/bot\u00e3o-compre-aqui.png 487w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1137\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-416x239.png 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-30x17.png 30w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-250x143.png 250w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem.png 711w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1138\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-300x170.png\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-300x170.png 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-416x236.png 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-768x435.png 768w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-30x17.png 30w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools-250x142.png 250w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/folha-de-estudo-num\u00e9rico-_familyhastools.png 949w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1139\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-300x300.jpg\" alt=\"\" width=\"227\" height=\"227\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-300x300.jpg 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-324x324.jpg 324w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-100x100.jpg 100w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-416x416.jpg 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-150x150.jpg 150w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-30x30.jpg 30w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n-250x250.jpg 250w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28753707_1734852046553106_4862605614246789120_n.jpg 640w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1140\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-300x300.jpg\" alt=\"\" width=\"227\" height=\"227\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-300x300.jpg 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-324x324.jpg 324w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-100x100.jpg 100w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-416x416.jpg 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-150x150.jpg 150w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-768x768.jpg 768w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-1024x1024.jpg 1024w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-30x30.jpg 30w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n-250x250.jpg 250w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/28754404_367942510351801_7841884304173957120_n.jpg 1080w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1141\" src=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-300x180.png\" alt=\"\" width=\"458\" height=\"275\" srcset=\"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-300x180.png 300w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-416x250.png 416w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-768x461.png 768w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-1024x614.png 1024w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-1200x720.png 1200w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-30x18.png 30w, https:\/\/www.familyhastools.com\/wp-content\/uploads\/2018\/08\/conjunto-produtos-250x150.png 250w\" sizes=\"auto, (max-width: 458px) 100vw, 458px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esse produto foi desenvolvido especialmente para auxilar nas li\u00e7\u00f5es de matem\u00e1tica e facilitar o aprendizado. Nele est\u00e3o inclusos: Flash cards: n\u00fameros 0 a 30. Livros dos n\u00fameros: 0 a 30 (onde a crian\u00e7a pode usar a criatividade para preencher o livro e fixar o conceito numeral). Flash cards Jumbo: n\u00fameros 0 a 30. (possui adicional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1132","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools\" \/>\n<meta property=\"og:description\" content=\"Esse produto foi desenvolvido especialmente para auxilar nas li\u00e7\u00f5es de matem\u00e1tica e facilitar o aprendizado. Nele est\u00e3o inclusos: Flash cards: n\u00fameros 0 a 30. Livros dos n\u00fameros: 0 a 30 (onde a crian\u00e7a pode usar a criatividade para preencher o livro e fixar o conceito numeral). Flash cards Jumbo: n\u00fameros 0 a 30. (possui adicional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/\" \/>\n<meta property=\"og:site_name\" content=\"Family Has Tools\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-03T16:47:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-03T17:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png\" \/>\n<meta name=\"author\" content=\"family\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"family\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/\"},\"author\":{\"name\":\"family\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/person\\\/a01a697a964cf58afe89feae4136a034\"},\"headline\":\"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica\",\"datePublished\":\"2018-08-03T16:47:28+00:00\",\"dateModified\":\"2018-08-03T17:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/\"},\"wordCount\":91,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/familyhastools.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/flash-cards-jumbo-imagem-300x172.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/\",\"name\":\"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/familyhastools.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/flash-cards-jumbo-imagem-300x172.png\",\"datePublished\":\"2018-08-03T16:47:28+00:00\",\"dateModified\":\"2018-08-03T17:43:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#primaryimage\",\"url\":\"http:\\\/\\\/familyhastools.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/flash-cards-jumbo-imagem-300x172.png\",\"contentUrl\":\"http:\\\/\\\/familyhastools.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/flash-cards-jumbo-imagem-300x172.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/2018\\\/08\\\/03\\\/1132\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.familyhastools.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#website\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/\",\"name\":\"Family Has Tools\",\"description\":\"A jornada de nossa familia homeschooler\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.familyhastools.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#organization\",\"name\":\"Family Has Tools\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-com-Arthur-_grande.png\",\"contentUrl\":\"https:\\\/\\\/www.familyhastools.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-com-Arthur-_grande.png\",\"width\":2350,\"height\":1000,\"caption\":\"Family Has Tools\"},\"image\":{\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.familyhastools.com\\\/#\\\/schema\\\/person\\\/a01a697a964cf58afe89feae4136a034\",\"name\":\"family\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g\",\"caption\":\"family\"},\"sameAs\":[\"http:\\\/\\\/www.familyhastools.com\"],\"url\":\"https:\\\/\\\/www.familyhastools.com\\\/index.php\\\/author\\\/family-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/","og_locale":"pt_BR","og_type":"article","og_title":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools","og_description":"Esse produto foi desenvolvido especialmente para auxilar nas li\u00e7\u00f5es de matem\u00e1tica e facilitar o aprendizado. Nele est\u00e3o inclusos: Flash cards: n\u00fameros 0 a 30. Livros dos n\u00fameros: 0 a 30 (onde a crian\u00e7a pode usar a criatividade para preencher o livro e fixar o conceito numeral). Flash cards Jumbo: n\u00fameros 0 a 30. (possui adicional [&hellip;]","og_url":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/","og_site_name":"Family Has Tools","article_published_time":"2018-08-03T16:47:28+00:00","article_modified_time":"2018-08-03T17:43:27+00:00","og_image":[{"url":"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png","type":"","width":"","height":""}],"author":"family","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"family"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#article","isPartOf":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/"},"author":{"name":"family","@id":"https:\/\/www.familyhastools.com\/#\/schema\/person\/a01a697a964cf58afe89feae4136a034"},"headline":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica","datePublished":"2018-08-03T16:47:28+00:00","dateModified":"2018-08-03T17:43:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/"},"wordCount":91,"commentCount":0,"publisher":{"@id":"https:\/\/www.familyhastools.com\/#organization"},"image":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#primaryimage"},"thumbnailUrl":"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png","articleSection":["Uncategorized"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/","url":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/","name":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica - Family Has Tools","isPartOf":{"@id":"https:\/\/www.familyhastools.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#primaryimage"},"image":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#primaryimage"},"thumbnailUrl":"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png","datePublished":"2018-08-03T16:47:28+00:00","dateModified":"2018-08-03T17:43:27+00:00","breadcrumb":{"@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#primaryimage","url":"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png","contentUrl":"http:\/\/familyhastools.com\/wp-content\/uploads\/2018\/08\/flash-cards-jumbo-imagem-300x172.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.familyhastools.com\/index.php\/2018\/08\/03\/1132\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.familyhastools.com\/"},{"@type":"ListItem","position":2,"name":"N\u00fameros 0 a 30: Material de apoio para matem\u00e1tica"}]},{"@type":"WebSite","@id":"https:\/\/www.familyhastools.com\/#website","url":"https:\/\/www.familyhastools.com\/","name":"Family Has Tools","description":"A jornada de nossa familia homeschooler","publisher":{"@id":"https:\/\/www.familyhastools.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.familyhastools.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.familyhastools.com\/#organization","name":"Family Has Tools","url":"https:\/\/www.familyhastools.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","contentUrl":"https:\/\/www.familyhastools.com\/wp-content\/uploads\/2020\/05\/logo-com-Arthur-_grande.png","width":2350,"height":1000,"caption":"Family Has Tools"},"image":{"@id":"https:\/\/www.familyhastools.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.familyhastools.com\/#\/schema\/person\/a01a697a964cf58afe89feae4136a034","name":"family","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7051e6acb2f2fd4d6484f79119940f843cbfe9d9b6aa14d74f4011595780205?s=96&d=mm&r=g","caption":"family"},"sameAs":["http:\/\/www.familyhastools.com"],"url":"https:\/\/www.familyhastools.com\/index.php\/author\/family-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/posts\/1132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/comments?post=1132"}],"version-history":[{"count":5,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/posts\/1132\/revisions"}],"predecessor-version":[{"id":1143,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/posts\/1132\/revisions\/1143"}],"wp:attachment":[{"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/media?parent=1132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/categories?post=1132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familyhastools.com\/index.php\/wp-json\/wp\/v2\/tags?post=1132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}